{"id":59583,"date":"2023-01-19T00:11:18","date_gmt":"2023-01-18T21:11:18","guid":{"rendered":"https:\/\/alfaisalyfc.net\/?p=59583"},"modified":"2023-01-26T12:03:02","modified_gmt":"2023-01-26T09:03:02","slug":"%d8%a7%d9%84%d9%81%d9%8a%d8%b5%d9%84%d9%8a-%d9%8a%d8%aa%d8%b9%d8%a7%d8%af%d9%84-%d8%a7%d9%8a%d8%ac%d8%a7%d8%a8%d9%8a%d8%a7%d9%8b-%d8%a7%d9%85%d8%a7-%d8%a7%d9%84%d8%b4%d8%b9%d9%84%d8%a9","status":"publish","type":"post","link":"https:\/\/alfaisalyfc.net\/en\/first-team\/59583\/","title":{"rendered":"\u0627\u0644\u0641\u064a\u0635\u0644\u064a \u064a\u062a\u0639\u0627\u062f\u0644 \u0627\u064a\u062c\u0627\u0628\u064a\u0627\u064b \u0645\u0646 \u0627\u0645\u0627\u0645 \u0627\u0644\u0634\u0639\u0644\u0629"},"content":{"rendered":"<p class=\"p1\" dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #800000;\"><span class=\"s1\">Draw<\/span> <span class=\"s1\">\u0627\u0644\u0641\u0631\u064a\u0642<\/span> <span class=\"s1\">\u0627\u0644\u0623\u0648\u0644<\/span> <span class=\"s1\">\u0644\u0643\u0631\u0629<\/span> <span class=\"s1\">\u0627\u0644\u0642\u062f\u0645<\/span> <span class=\"s1\">\u0645\u0639<\/span> <span class=\"s1\">\u0646\u0638\u064a\u0631\u0647<\/span> <span class=\"s1\">&#8220;<\/span> <span class=\"s1\">\u0627\u0644\u0634\u0639\u0644\u0629<\/span> <span class=\"s1\">&#8220;<\/span> <span class=\"s1\">\u0628\u0647\u062f\u0641<\/span> <span class=\"s1\">\u0644\u0643\u0644<\/span><span class=\"s1\">\u0645\u0646\u0647\u0645\u0627<\/span> <span class=\"s1\">\u060c<\/span> <span class=\"s1\">\u0636\u0645\u0646<\/span> <span class=\"s1\">\u0645\u0628\u0627\u0631\u064a\u0627\u062a<\/span> <span class=\"s1\">\u0627\u0644\u062c\u0648\u0644\u0629<\/span> <span class=\"s1\">\u0627\u0644\u0633\u0627\u0628\u0639\u0629<\/span> <span class=\"s1\">\u0639\u0634\u0631<\/span> <span class=\"s1\">\u0645\u0646<\/span> <span class=\"s1\">\u062f\u0648\u0631\u064a<\/span> <span class=\"s1\">\u064a\u0644\u0648<\/span><span class=\"s1\">\u0644\u0644\u062f\u0631\u062c\u0629<\/span> <span class=\"s1\">\u0627\u0644\u0623\u0648\u0644\u0649<\/span> <span class=\"s1\">\u060c<\/span> <span class=\"s1\">\u0641\u064a<\/span> <span class=\"s1\">\u0644\u0642\u0627\u0621<\/span> <span class=\"s1\">\u062c\u0645\u0639\u0647\u0645\u0627<\/span> <span class=\"s1\">\u0639\u0644\u0649<\/span> <span class=\"s1\">\u0623\u0631\u0636\u064a\u0629<\/span> <span class=\"s1\">\u0645\u0644\u0639\u0628<\/span> <span class=\"s1\">\u0645\u062f\u064a\u0646\u0629<\/span><span class=\"s1\">\u0627\u0644\u0645\u062c\u0645\u0639\u0629<\/span> <span class=\"s1\">\u0627\u0644\u0631\u064a\u0627\u0636\u064a\u0629<\/span> <span class=\"s1\">\u0627\u0644\u064a\u0648\u0645<\/span> <span class=\"s1\">\u0627\u0644\u0623\u0631\u0628\u0639\u0627\u0621<\/span><span class=\"s2\"> .<\/span><\/span><\/p>\n<p class=\"p3\" dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #800000;\"><span class=\"s4\">\u0648\u0633\u062c\u0644<\/span> <span class=\"s4\">Goal<\/span> <span class=\"s4\">\u0627\u0644\u0639\u0646\u0627\u0628\u064a<\/span> <span class=\"s4\">\u0627\u0644\u0644\u0627\u0639\u0628<\/span> <span class=\"s4\">\u0635\u0627\u0644\u062d<\/span> <span class=\"s4\">\u0627\u0644\u0642\u0645\u064a\u0632\u064a<\/span> <span class=\"s4\">\u0639\u0646\u062f<\/span> <span class=\"s4\">\u0627\u0644\u062f\u0642\u064a\u0642\u0629<\/span><span class=\"s3\"> 64 <\/span><span class=\"s4\">\u0645\u0646<\/span> <span class=\"s4\">\u0632\u0645\u0646<\/span> <span class=\"s4\">\u0627\u0644\u0644\u0642\u0627\u0621<\/span><span class=\"s3\">. <\/span><\/span><\/p>\n<p class=\"p3\" dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #800000;\"><span class=\"s4\">\u0648\u0631\u0641\u0639<\/span> <span class=\"s4\">\u0627\u0644\u0641\u0631\u064a\u0642<\/span> <span class=\"s4\">\u0631\u0635\u064a\u062f\u0647<\/span> <span class=\"s4\">\u0625\u0644\u0649<\/span> <span class=\"s4\">\u0627\u0644\u0646\u0642\u0637\u0629<\/span><span class=\"s3\"> 34 <\/span><span class=\"s4\">\u0641\u064a<\/span> <span class=\"s4\">\u0635\u062f\u0627\u0631\u0629<\/span> <span class=\"s4\">\u0627\u0644\u062a\u0631\u062a\u064a\u0628<\/span><span class=\"s3\">.<\/span><\/span><\/p>\n<p class=\"p3\" dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #800000;\"><span class=\"s4\">\u0647\u0630\u0627<\/span> <span class=\"s4\">\u0648\u0633\u064a\u0648\u0627\u062c\u0647<\/span> <span class=\"s4\">\u0627\u0644\u0641\u0631\u064a\u0642<\/span> <span class=\"s4\">\u0645\u0633\u0627\u0621<\/span> <span class=\"s4\">\u064a\u0648\u0645<\/span> <span class=\"s4\">\u0627\u0644\u062c\u0645\u0639\u0629<\/span> <span class=\"s4\">\u0627\u0644\u0645\u0642\u0628\u0644<\/span> <span class=\"s4\">\u0646\u0627\u062f\u064a<\/span> <span class=\"s4\">\u0627\u0644\u0631\u064a\u0627\u0636<\/span> <span class=\"s4\">\u0636\u0645\u0646<\/span> <span class=\"s4\">\u0645\u0628\u0627\u0631\u064a\u0627\u062a<\/span> <span class=\"s4\">\u0627\u0644\u062c\u0648\u0644\u0629<\/span> <span class=\"s4\">\u0627\u0644\u062b\u0627\u0645\u0646\u0629<\/span> <span class=\"s4\">\u0639\u0634\u0631<\/span> <span class=\"s4\">\u0645\u0646<\/span> <span class=\"s4\">\u062f\u0648\u0631\u064a<\/span> <span class=\"s4\">\u064a\u0644\u0648<\/span><span class=\"s3\">.<\/span><\/span><\/p>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 840px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 10px;      padding-top: 10px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 415px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 10px;       margin-bottom: 10px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 55.421686746988%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails\"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/en\/wp-json\/wp\/v2\/posts\/59583\"         data-lightbox-url=\"https:\/\/alfaisalyfc.net\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=806&#038;tag=0&#038;theme_id=1&#038;shortcode_id=2237&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fen%2Fwp-json%2Fwp%2Fv2%2Fposts%2F59583\"         data-gallery-id=\"806\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"2237\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"806\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/alfaisalyfc.net\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\" data-trp-original-action=\"#\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"2\"         data-thumbnail-width=\"415\"         data-bwg=\"0\"         data-gallery-id=\"806\"         data-lightbox-url=\"https:\/\/alfaisalyfc.net\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=806&amp;tag=0&amp;theme_id=1&amp;shortcode_id=2237&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fen%2Fwp-json%2Fwp%2Fv2%2Fposts%2F59583\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21888\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/B3209EF6-1E79-4B20-BCD8-31D0F3BC5D57.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21888\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/B3209EF6-1E79-4B20-BCD8-31D0F3BC5D57.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/B3209EF6-1E79-4B20-BCD8-31D0F3BC5D57.jpeg?bwg=1674075910\"                   alt=\"B3209EF6-1E79-4B20-BCD8-31D0F3BC5D57\"                   title=\"B3209EF6-1E79-4B20-BCD8-31D0F3BC5D57\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21889\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/E8CA6FE0-72ED-4B4D-8B6E-8C67DB21B705.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21889\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/E8CA6FE0-72ED-4B4D-8B6E-8C67DB21B705.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/E8CA6FE0-72ED-4B4D-8B6E-8C67DB21B705.jpeg?bwg=1674075910\"                   alt=\"E8CA6FE0-72ED-4B4D-8B6E-8C67DB21B705\"                   title=\"E8CA6FE0-72ED-4B4D-8B6E-8C67DB21B705\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21890\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/9BC469B9-C979-4C0F-8CCE-C36FEE3F98CF.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21890\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/9BC469B9-C979-4C0F-8CCE-C36FEE3F98CF.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/9BC469B9-C979-4C0F-8CCE-C36FEE3F98CF.jpeg?bwg=1674075910\"                   alt=\"9BC469B9-C979-4C0F-8CCE-C36FEE3F98CF\"                   title=\"9BC469B9-C979-4C0F-8CCE-C36FEE3F98CF\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21891\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/B0AA3360-9147-4DC8-AD1D-323488746154.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21891\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/B0AA3360-9147-4DC8-AD1D-323488746154.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/B0AA3360-9147-4DC8-AD1D-323488746154.jpeg?bwg=1674075910\"                   alt=\"B0AA3360-9147-4DC8-AD1D-323488746154\"                   title=\"B0AA3360-9147-4DC8-AD1D-323488746154\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21892\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/FDDA0B88-1380-47E9-B078-13A18C5B4720.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21892\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/FDDA0B88-1380-47E9-B078-13A18C5B4720.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/FDDA0B88-1380-47E9-B078-13A18C5B4720.jpeg?bwg=1674075910\"                   alt=\"FDDA0B88-1380-47E9-B078-13A18C5B4720\"                   title=\"FDDA0B88-1380-47E9-B078-13A18C5B4720\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21893\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/3077A779-9F46-423A-B135-D5147A71C965.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21893\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/3077A779-9F46-423A-B135-D5147A71C965.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/3077A779-9F46-423A-B135-D5147A71C965.jpeg?bwg=1674075910\"                   alt=\"3077A779-9F46-423A-B135-D5147A71C965\"                   title=\"3077A779-9F46-423A-B135-D5147A71C965\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21894\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/A6D6CC99-54BB-4C98-B916-C5C2C3D4607A.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21894\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A6D6CC99-54BB-4C98-B916-C5C2C3D4607A.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A6D6CC99-54BB-4C98-B916-C5C2C3D4607A.jpeg?bwg=1674075910\"                   alt=\"A6D6CC99-54BB-4C98-B916-C5C2C3D4607A\"                   title=\"A6D6CC99-54BB-4C98-B916-C5C2C3D4607A\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21895\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/13176B49-8121-4F6B-8C4B-0D5222C6CA0F.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21895\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/13176B49-8121-4F6B-8C4B-0D5222C6CA0F.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/13176B49-8121-4F6B-8C4B-0D5222C6CA0F.jpeg?bwg=1674075910\"                   alt=\"13176B49-8121-4F6B-8C4B-0D5222C6CA0F\"                   title=\"13176B49-8121-4F6B-8C4B-0D5222C6CA0F\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21896\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/985ACBD3-8705-4F56-A366-A0F6C0AA0D74.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21896\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/985ACBD3-8705-4F56-A366-A0F6C0AA0D74.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/985ACBD3-8705-4F56-A366-A0F6C0AA0D74.jpeg?bwg=1674075910\"                   alt=\"985ACBD3-8705-4F56-A366-A0F6C0AA0D74\"                   title=\"985ACBD3-8705-4F56-A366-A0F6C0AA0D74\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21897\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/0D8E422F-EF07-4D3F-9693-D53C90943072.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21897\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0D8E422F-EF07-4D3F-9693-D53C90943072.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0D8E422F-EF07-4D3F-9693-D53C90943072.jpeg?bwg=1674075910\"                   alt=\"0D8E422F-EF07-4D3F-9693-D53C90943072\"                   title=\"0D8E422F-EF07-4D3F-9693-D53C90943072\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21898\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/FB7BAEF1-23F8-407A-808A-436B214F9CB0.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21898\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/FB7BAEF1-23F8-407A-808A-436B214F9CB0.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/FB7BAEF1-23F8-407A-808A-436B214F9CB0.jpeg?bwg=1674075910\"                   alt=\"FB7BAEF1-23F8-407A-808A-436B214F9CB0\"                   title=\"FB7BAEF1-23F8-407A-808A-436B214F9CB0\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21899\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/152AF4FB-AABC-4A73-9E3D-EDDE2E47CB6D.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21899\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/152AF4FB-AABC-4A73-9E3D-EDDE2E47CB6D.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/152AF4FB-AABC-4A73-9E3D-EDDE2E47CB6D.jpeg?bwg=1674075910\"                   alt=\"152AF4FB-AABC-4A73-9E3D-EDDE2E47CB6D\"                   title=\"152AF4FB-AABC-4A73-9E3D-EDDE2E47CB6D\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21900\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/AFF0F970-0F03-4B2C-9BCA-530E53DA61D0.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21900\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AFF0F970-0F03-4B2C-9BCA-530E53DA61D0.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AFF0F970-0F03-4B2C-9BCA-530E53DA61D0.jpeg?bwg=1674075910\"                   alt=\"AFF0F970-0F03-4B2C-9BCA-530E53DA61D0\"                   title=\"AFF0F970-0F03-4B2C-9BCA-530E53DA61D0\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21901\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2C7CA971-5E5C-4A49-9390-D957A1452202.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21901\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2C7CA971-5E5C-4A49-9390-D957A1452202.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2C7CA971-5E5C-4A49-9390-D957A1452202.jpeg?bwg=1674075910\"                   alt=\"2C7CA971-5E5C-4A49-9390-D957A1452202\"                   title=\"2C7CA971-5E5C-4A49-9390-D957A1452202\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21902\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/839A4222-8A67-4A14-BD0C-8918429DD33E.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21902\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/839A4222-8A67-4A14-BD0C-8918429DD33E.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/839A4222-8A67-4A14-BD0C-8918429DD33E.jpeg?bwg=1674075910\"                   alt=\"839A4222-8A67-4A14-BD0C-8918429DD33E\"                   title=\"839A4222-8A67-4A14-BD0C-8918429DD33E\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21903\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/68880C44-4FFA-4228-B95F-DE91C87870BE.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21903\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/68880C44-4FFA-4228-B95F-DE91C87870BE.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/68880C44-4FFA-4228-B95F-DE91C87870BE.jpeg?bwg=1674075910\"                   alt=\"68880C44-4FFA-4228-B95F-DE91C87870BE\"                   title=\"68880C44-4FFA-4228-B95F-DE91C87870BE\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21904\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/C9F0FCFC-49AD-430D-83AB-4D5F7B84F9AB.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21904\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C9F0FCFC-49AD-430D-83AB-4D5F7B84F9AB.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C9F0FCFC-49AD-430D-83AB-4D5F7B84F9AB.jpeg?bwg=1674075910\"                   alt=\"C9F0FCFC-49AD-430D-83AB-4D5F7B84F9AB\"                   title=\"C9F0FCFC-49AD-430D-83AB-4D5F7B84F9AB\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21905\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/CE96D8EE-5379-4116-A32E-EEFD519F2E9F.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21905\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/CE96D8EE-5379-4116-A32E-EEFD519F2E9F.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/CE96D8EE-5379-4116-A32E-EEFD519F2E9F.jpeg?bwg=1674075910\"                   alt=\"CE96D8EE-5379-4116-A32E-EEFD519F2E9F\"                   title=\"CE96D8EE-5379-4116-A32E-EEFD519F2E9F\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21906\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/7FE6E453-4C7C-45CC-8841-F74217209C34.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21906\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/7FE6E453-4C7C-45CC-8841-F74217209C34.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/7FE6E453-4C7C-45CC-8841-F74217209C34.jpeg?bwg=1674075910\"                   alt=\"7FE6E453-4C7C-45CC-8841-F74217209C34\"                   title=\"7FE6E453-4C7C-45CC-8841-F74217209C34\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21907\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/E04DD877-4D3F-4ABB-ADE9-A51BCDA1198A.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21907\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/E04DD877-4D3F-4ABB-ADE9-A51BCDA1198A.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/E04DD877-4D3F-4ABB-ADE9-A51BCDA1198A.jpeg?bwg=1674075910\"                   alt=\"E04DD877-4D3F-4ABB-ADE9-A51BCDA1198A\"                   title=\"E04DD877-4D3F-4ABB-ADE9-A51BCDA1198A\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21908\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/D188DF4A-8C44-4394-A122-C52D89FFBA11.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21908\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/D188DF4A-8C44-4394-A122-C52D89FFBA11.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/D188DF4A-8C44-4394-A122-C52D89FFBA11.jpeg?bwg=1674075910\"                   alt=\"D188DF4A-8C44-4394-A122-C52D89FFBA11\"                   title=\"D188DF4A-8C44-4394-A122-C52D89FFBA11\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21909\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/204454B6-429B-41A3-A716-47D4994B3C10.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21909\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/204454B6-429B-41A3-A716-47D4994B3C10.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/204454B6-429B-41A3-A716-47D4994B3C10.jpeg?bwg=1674075910\"                   alt=\"204454B6-429B-41A3-A716-47D4994B3C10\"                   title=\"204454B6-429B-41A3-A716-47D4994B3C10\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21910\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/B960B107-1C8F-4654-AD75-3DAF24CCA974.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21910\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/B960B107-1C8F-4654-AD75-3DAF24CCA974.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/B960B107-1C8F-4654-AD75-3DAF24CCA974.jpeg?bwg=1674075910\"                   alt=\"B960B107-1C8F-4654-AD75-3DAF24CCA974\"                   title=\"B960B107-1C8F-4654-AD75-3DAF24CCA974\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21911\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/48982F17-FE69-480F-BC9B-CAFD87EFAEEA.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21911\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/48982F17-FE69-480F-BC9B-CAFD87EFAEEA.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/48982F17-FE69-480F-BC9B-CAFD87EFAEEA.jpeg?bwg=1674075910\"                   alt=\"48982F17-FE69-480F-BC9B-CAFD87EFAEEA\"                   title=\"48982F17-FE69-480F-BC9B-CAFD87EFAEEA\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21912\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/3ACC770A-09E1-4051-9577-AC2605C57310.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21912\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/3ACC770A-09E1-4051-9577-AC2605C57310.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/3ACC770A-09E1-4051-9577-AC2605C57310.jpeg?bwg=1674075910\"                   alt=\"3ACC770A-09E1-4051-9577-AC2605C57310\"                   title=\"3ACC770A-09E1-4051-9577-AC2605C57310\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21913\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/815ED8EE-899D-4712-BF22-9E5513FB8FF3.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21913\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/815ED8EE-899D-4712-BF22-9E5513FB8FF3.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/815ED8EE-899D-4712-BF22-9E5513FB8FF3.jpeg?bwg=1674075910\"                   alt=\"815ED8EE-899D-4712-BF22-9E5513FB8FF3\"                   title=\"815ED8EE-899D-4712-BF22-9E5513FB8FF3\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21914\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/770CF2D5-6075-45DC-A91C-FE1CDF4CCE21.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21914\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/770CF2D5-6075-45DC-A91C-FE1CDF4CCE21.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/770CF2D5-6075-45DC-A91C-FE1CDF4CCE21.jpeg?bwg=1674075910\"                   alt=\"770CF2D5-6075-45DC-A91C-FE1CDF4CCE21\"                   title=\"770CF2D5-6075-45DC-A91C-FE1CDF4CCE21\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21915\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/77779360-942A-4DDE-95E5-7426B0786A59.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21915\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/77779360-942A-4DDE-95E5-7426B0786A59.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/77779360-942A-4DDE-95E5-7426B0786A59.jpeg?bwg=1674075910\"                   alt=\"77779360-942A-4DDE-95E5-7426B0786A59\"                   title=\"77779360-942A-4DDE-95E5-7426B0786A59\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21916\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/501DA04F-A564-48DA-B962-4D34E99045EE.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21916\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/501DA04F-A564-48DA-B962-4D34E99045EE.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/501DA04F-A564-48DA-B962-4D34E99045EE.jpeg?bwg=1674075910\"                   alt=\"501DA04F-A564-48DA-B962-4D34E99045EE\"                   title=\"501DA04F-A564-48DA-B962-4D34E99045EE\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21917\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/200F2AAE-E5AC-4E05-A322-E92C2DCC2B3C.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21917\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/200F2AAE-E5AC-4E05-A322-E92C2DCC2B3C.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/200F2AAE-E5AC-4E05-A322-E92C2DCC2B3C.jpeg?bwg=1674075910\"                   alt=\"200F2AAE-E5AC-4E05-A322-E92C2DCC2B3C\"                   title=\"200F2AAE-E5AC-4E05-A322-E92C2DCC2B3C\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21918\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/A9F32C99-5A93-46F4-B67E-20704F6DF78F.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21918\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A9F32C99-5A93-46F4-B67E-20704F6DF78F.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A9F32C99-5A93-46F4-B67E-20704F6DF78F.jpeg?bwg=1674075910\"                   alt=\"A9F32C99-5A93-46F4-B67E-20704F6DF78F\"                   title=\"A9F32C99-5A93-46F4-B67E-20704F6DF78F\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21919\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/E19C847E-C13F-4297-918D-AC2A953654B0.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21919\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/E19C847E-C13F-4297-918D-AC2A953654B0.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/E19C847E-C13F-4297-918D-AC2A953654B0.jpeg?bwg=1674075910\"                   alt=\"E19C847E-C13F-4297-918D-AC2A953654B0\"                   title=\"E19C847E-C13F-4297-918D-AC2A953654B0\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21920\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/4CC14F2A-6920-4E41-AA2B-A08D1143BD59.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21920\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/4CC14F2A-6920-4E41-AA2B-A08D1143BD59.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/4CC14F2A-6920-4E41-AA2B-A08D1143BD59.jpeg?bwg=1674075910\"                   alt=\"4CC14F2A-6920-4E41-AA2B-A08D1143BD59\"                   title=\"4CC14F2A-6920-4E41-AA2B-A08D1143BD59\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21921\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/0511838E-D686-4C3B-B97D-4DED86922FB2.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21921\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0511838E-D686-4C3B-B97D-4DED86922FB2.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0511838E-D686-4C3B-B97D-4DED86922FB2.jpeg?bwg=1674075910\"                   alt=\"0511838E-D686-4C3B-B97D-4DED86922FB2\"                   title=\"0511838E-D686-4C3B-B97D-4DED86922FB2\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21922\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/AB787EB3-61B3-4F60-A8A4-25C1F45C51D0.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21922\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AB787EB3-61B3-4F60-A8A4-25C1F45C51D0.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AB787EB3-61B3-4F60-A8A4-25C1F45C51D0.jpeg?bwg=1674075910\"                   alt=\"AB787EB3-61B3-4F60-A8A4-25C1F45C51D0\"                   title=\"AB787EB3-61B3-4F60-A8A4-25C1F45C51D0\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21923\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/D61B2930-F9A3-4CE5-9EE6-E909AB2BED6A.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21923\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/D61B2930-F9A3-4CE5-9EE6-E909AB2BED6A.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/D61B2930-F9A3-4CE5-9EE6-E909AB2BED6A.jpeg?bwg=1674075910\"                   alt=\"D61B2930-F9A3-4CE5-9EE6-E909AB2BED6A\"                   title=\"D61B2930-F9A3-4CE5-9EE6-E909AB2BED6A\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21924\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/41B37826-6B09-4A03-994A-9B827EBD6533.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21924\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/41B37826-6B09-4A03-994A-9B827EBD6533.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/41B37826-6B09-4A03-994A-9B827EBD6533.jpeg?bwg=1674075910\"                   alt=\"41B37826-6B09-4A03-994A-9B827EBD6533\"                   title=\"41B37826-6B09-4A03-994A-9B827EBD6533\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21925\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/FFF96C78-82EF-4B39-BD76-921BE697D7F3.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21925\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/FFF96C78-82EF-4B39-BD76-921BE697D7F3.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/FFF96C78-82EF-4B39-BD76-921BE697D7F3.jpeg?bwg=1674075910\"                   alt=\"FFF96C78-82EF-4B39-BD76-921BE697D7F3\"                   title=\"FFF96C78-82EF-4B39-BD76-921BE697D7F3\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21926\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/D7E2D9FA-C10E-4614-A1F6-36BF5C33C98C.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21926\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/D7E2D9FA-C10E-4614-A1F6-36BF5C33C98C.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/D7E2D9FA-C10E-4614-A1F6-36BF5C33C98C.jpeg?bwg=1674075910\"                   alt=\"D7E2D9FA-C10E-4614-A1F6-36BF5C33C98C\"                   title=\"D7E2D9FA-C10E-4614-A1F6-36BF5C33C98C\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21927\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/357360CC-E62D-47B1-9EA5-C17DE29FAE87.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21927\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/357360CC-E62D-47B1-9EA5-C17DE29FAE87.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/357360CC-E62D-47B1-9EA5-C17DE29FAE87.jpeg?bwg=1674075910\"                   alt=\"357360CC-E62D-47B1-9EA5-C17DE29FAE87\"                   title=\"357360CC-E62D-47B1-9EA5-C17DE29FAE87\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21928\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/6D710315-8B95-4B7D-9714-0CAA090A52E8.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21928\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/6D710315-8B95-4B7D-9714-0CAA090A52E8.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/6D710315-8B95-4B7D-9714-0CAA090A52E8.jpeg?bwg=1674075910\"                   alt=\"6D710315-8B95-4B7D-9714-0CAA090A52E8\"                   title=\"6D710315-8B95-4B7D-9714-0CAA090A52E8\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21929\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2C843B95-37DF-403A-8713-368969438921.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21929\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2C843B95-37DF-403A-8713-368969438921.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2C843B95-37DF-403A-8713-368969438921.jpeg?bwg=1674075910\"                   alt=\"2C843B95-37DF-403A-8713-368969438921\"                   title=\"2C843B95-37DF-403A-8713-368969438921\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21930\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/7E2C0661-4C96-4A86-A25E-B7BE0114DF4E.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21930\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/7E2C0661-4C96-4A86-A25E-B7BE0114DF4E.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/7E2C0661-4C96-4A86-A25E-B7BE0114DF4E.jpeg?bwg=1674075910\"                   alt=\"7E2C0661-4C96-4A86-A25E-B7BE0114DF4E\"                   title=\"7E2C0661-4C96-4A86-A25E-B7BE0114DF4E\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21931\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/DEE34C42-C017-4275-817B-DD9E68D0F5C6.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21931\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/DEE34C42-C017-4275-817B-DD9E68D0F5C6.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/DEE34C42-C017-4275-817B-DD9E68D0F5C6.jpeg?bwg=1674075910\"                   alt=\"DEE34C42-C017-4275-817B-DD9E68D0F5C6\"                   title=\"DEE34C42-C017-4275-817B-DD9E68D0F5C6\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21932\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/27CD8AD9-DB54-4AED-A972-A13B586DE578.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21932\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/27CD8AD9-DB54-4AED-A972-A13B586DE578.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/27CD8AD9-DB54-4AED-A972-A13B586DE578.jpeg?bwg=1674075910\"                   alt=\"27CD8AD9-DB54-4AED-A972-A13B586DE578\"                   title=\"27CD8AD9-DB54-4AED-A972-A13B586DE578\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21933\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/45985F78-05D4-4C14-8B64-A675FDFD7AC8.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21933\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/45985F78-05D4-4C14-8B64-A675FDFD7AC8.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/45985F78-05D4-4C14-8B64-A675FDFD7AC8.jpeg?bwg=1674075910\"                   alt=\"45985F78-05D4-4C14-8B64-A675FDFD7AC8\"                   title=\"45985F78-05D4-4C14-8B64-A675FDFD7AC8\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21934\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/0F54D8B6-A6A7-4F22-B66A-B271BFAD2A39.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21934\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0F54D8B6-A6A7-4F22-B66A-B271BFAD2A39.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0F54D8B6-A6A7-4F22-B66A-B271BFAD2A39.jpeg?bwg=1674075910\"                   alt=\"0F54D8B6-A6A7-4F22-B66A-B271BFAD2A39\"                   title=\"0F54D8B6-A6A7-4F22-B66A-B271BFAD2A39\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21935\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/A7C18214-E635-4C1E-8CE3-A36ED9843CE7.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21935\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A7C18214-E635-4C1E-8CE3-A36ED9843CE7.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A7C18214-E635-4C1E-8CE3-A36ED9843CE7.jpeg?bwg=1674075910\"                   alt=\"A7C18214-E635-4C1E-8CE3-A36ED9843CE7\"                   title=\"A7C18214-E635-4C1E-8CE3-A36ED9843CE7\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21936\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/713ED716-86B1-48A9-B92D-72046F1C2524.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21936\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/713ED716-86B1-48A9-B92D-72046F1C2524.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/713ED716-86B1-48A9-B92D-72046F1C2524.jpeg?bwg=1674075910\"                   alt=\"713ED716-86B1-48A9-B92D-72046F1C2524\"                   title=\"713ED716-86B1-48A9-B92D-72046F1C2524\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21937\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2F23AB0F-C79F-4012-B148-2E660321B464.jpeg?bwg=1674075910\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21937\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2F23AB0F-C79F-4012-B148-2E660321B464.jpeg?bwg=1674075910\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2F23AB0F-C79F-4012-B148-2E660321B464.jpeg?bwg=1674075910\"                   alt=\"2F23AB0F-C79F-4012-B148-2E660321B464\"                   title=\"2F23AB0F-C79F-4012-B148-2E660321B464\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21938\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/5DF64B5E-ACFA-47D9-8246-37876A04E9BE.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21938\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/5DF64B5E-ACFA-47D9-8246-37876A04E9BE.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/5DF64B5E-ACFA-47D9-8246-37876A04E9BE.jpeg?bwg=1674075912\"                   alt=\"5DF64B5E-ACFA-47D9-8246-37876A04E9BE\"                   title=\"5DF64B5E-ACFA-47D9-8246-37876A04E9BE\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21939\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/459E93A4-B197-4C17-AFCB-10280EF66F8C.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21939\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/459E93A4-B197-4C17-AFCB-10280EF66F8C.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/459E93A4-B197-4C17-AFCB-10280EF66F8C.jpeg?bwg=1674075912\"                   alt=\"459E93A4-B197-4C17-AFCB-10280EF66F8C\"                   title=\"459E93A4-B197-4C17-AFCB-10280EF66F8C\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21940\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/8F60B3C3-9D6F-4B3D-B51F-68EDE3F2B6EC.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21940\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/8F60B3C3-9D6F-4B3D-B51F-68EDE3F2B6EC.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/8F60B3C3-9D6F-4B3D-B51F-68EDE3F2B6EC.jpeg?bwg=1674075912\"                   alt=\"8F60B3C3-9D6F-4B3D-B51F-68EDE3F2B6EC\"                   title=\"8F60B3C3-9D6F-4B3D-B51F-68EDE3F2B6EC\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21941\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/29FD2B64-4509-4DFA-A5F8-4B847CB608DF.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21941\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/29FD2B64-4509-4DFA-A5F8-4B847CB608DF.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/29FD2B64-4509-4DFA-A5F8-4B847CB608DF.jpeg?bwg=1674075912\"                   alt=\"29FD2B64-4509-4DFA-A5F8-4B847CB608DF\"                   title=\"29FD2B64-4509-4DFA-A5F8-4B847CB608DF\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21942\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/C6F09EA7-4BB4-49CC-BA1F-8AC3B29DEB61.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21942\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C6F09EA7-4BB4-49CC-BA1F-8AC3B29DEB61.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C6F09EA7-4BB4-49CC-BA1F-8AC3B29DEB61.jpeg?bwg=1674075912\"                   alt=\"C6F09EA7-4BB4-49CC-BA1F-8AC3B29DEB61\"                   title=\"C6F09EA7-4BB4-49CC-BA1F-8AC3B29DEB61\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21943\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/7D93BAC0-D3B3-4F6D-9427-39742BA7174E.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21943\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/7D93BAC0-D3B3-4F6D-9427-39742BA7174E.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/7D93BAC0-D3B3-4F6D-9427-39742BA7174E.jpeg?bwg=1674075912\"                   alt=\"7D93BAC0-D3B3-4F6D-9427-39742BA7174E\"                   title=\"7D93BAC0-D3B3-4F6D-9427-39742BA7174E\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21944\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/1F755CA5-B982-4F75-B9CB-F7092ED18C60.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21944\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/1F755CA5-B982-4F75-B9CB-F7092ED18C60.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/1F755CA5-B982-4F75-B9CB-F7092ED18C60.jpeg?bwg=1674075912\"                   alt=\"1F755CA5-B982-4F75-B9CB-F7092ED18C60\"                   title=\"1F755CA5-B982-4F75-B9CB-F7092ED18C60\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21945\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/AB7B1011-2E80-4791-826C-5A12D3894787.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21945\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AB7B1011-2E80-4791-826C-5A12D3894787.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AB7B1011-2E80-4791-826C-5A12D3894787.jpeg?bwg=1674075912\"                   alt=\"AB7B1011-2E80-4791-826C-5A12D3894787\"                   title=\"AB7B1011-2E80-4791-826C-5A12D3894787\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21946\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2D7335CF-DBE4-418A-8422-C3BFDACD9F5F.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21946\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2D7335CF-DBE4-418A-8422-C3BFDACD9F5F.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2D7335CF-DBE4-418A-8422-C3BFDACD9F5F.jpeg?bwg=1674075912\"                   alt=\"2D7335CF-DBE4-418A-8422-C3BFDACD9F5F\"                   title=\"2D7335CF-DBE4-418A-8422-C3BFDACD9F5F\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21947\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/C353E2F7-4832-40AD-8215-CFB24DE04858.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21947\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C353E2F7-4832-40AD-8215-CFB24DE04858.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C353E2F7-4832-40AD-8215-CFB24DE04858.jpeg?bwg=1674075912\"                   alt=\"C353E2F7-4832-40AD-8215-CFB24DE04858\"                   title=\"C353E2F7-4832-40AD-8215-CFB24DE04858\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21948\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/22E6FFFF-3CDD-4CAB-A17A-0B2F0BF8EA83.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21948\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/22E6FFFF-3CDD-4CAB-A17A-0B2F0BF8EA83.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/22E6FFFF-3CDD-4CAB-A17A-0B2F0BF8EA83.jpeg?bwg=1674075912\"                   alt=\"22E6FFFF-3CDD-4CAB-A17A-0B2F0BF8EA83\"                   title=\"22E6FFFF-3CDD-4CAB-A17A-0B2F0BF8EA83\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21949\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/5F77AA6B-E3E8-42CB-9C74-B6FB77E25A5E.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21949\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/5F77AA6B-E3E8-42CB-9C74-B6FB77E25A5E.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/5F77AA6B-E3E8-42CB-9C74-B6FB77E25A5E.jpeg?bwg=1674075912\"                   alt=\"5F77AA6B-E3E8-42CB-9C74-B6FB77E25A5E\"                   title=\"5F77AA6B-E3E8-42CB-9C74-B6FB77E25A5E\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21950\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/8BB8785F-B7B1-46BE-AB43-1AE82CDB8279.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21950\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/8BB8785F-B7B1-46BE-AB43-1AE82CDB8279.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/8BB8785F-B7B1-46BE-AB43-1AE82CDB8279.jpeg?bwg=1674075912\"                   alt=\"8BB8785F-B7B1-46BE-AB43-1AE82CDB8279\"                   title=\"8BB8785F-B7B1-46BE-AB43-1AE82CDB8279\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21951\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/64DAA69D-B055-429F-B61F-EDF68CE9849F.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21951\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/64DAA69D-B055-429F-B61F-EDF68CE9849F.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/64DAA69D-B055-429F-B61F-EDF68CE9849F.jpeg?bwg=1674075912\"                   alt=\"64DAA69D-B055-429F-B61F-EDF68CE9849F\"                   title=\"64DAA69D-B055-429F-B61F-EDF68CE9849F\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21952\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/19A8B257-3F22-44A4-859F-265554375FAC.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21952\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/19A8B257-3F22-44A4-859F-265554375FAC.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/19A8B257-3F22-44A4-859F-265554375FAC.jpeg?bwg=1674075912\"                   alt=\"19A8B257-3F22-44A4-859F-265554375FAC\"                   title=\"19A8B257-3F22-44A4-859F-265554375FAC\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21953\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/87699200-B94B-4921-A0F0-8105671EF162.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21953\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/87699200-B94B-4921-A0F0-8105671EF162.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/87699200-B94B-4921-A0F0-8105671EF162.jpeg?bwg=1674075912\"                   alt=\"87699200-B94B-4921-A0F0-8105671EF162\"                   title=\"87699200-B94B-4921-A0F0-8105671EF162\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21954\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/131D5A2F-6BD4-4B8D-B764-FDA78FA87152.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21954\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/131D5A2F-6BD4-4B8D-B764-FDA78FA87152.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/131D5A2F-6BD4-4B8D-B764-FDA78FA87152.jpeg?bwg=1674075912\"                   alt=\"131D5A2F-6BD4-4B8D-B764-FDA78FA87152\"                   title=\"131D5A2F-6BD4-4B8D-B764-FDA78FA87152\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21955\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/CADA05E0-3016-4059-AAEB-E102B72435A6.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21955\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/CADA05E0-3016-4059-AAEB-E102B72435A6.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/CADA05E0-3016-4059-AAEB-E102B72435A6.jpeg?bwg=1674075912\"                   alt=\"CADA05E0-3016-4059-AAEB-E102B72435A6\"                   title=\"CADA05E0-3016-4059-AAEB-E102B72435A6\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21956\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2E723E97-5230-4E4D-8DF2-79DC7015F714.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21956\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2E723E97-5230-4E4D-8DF2-79DC7015F714.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2E723E97-5230-4E4D-8DF2-79DC7015F714.jpeg?bwg=1674075912\"                   alt=\"2E723E97-5230-4E4D-8DF2-79DC7015F714\"                   title=\"2E723E97-5230-4E4D-8DF2-79DC7015F714\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21957\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/915BF0B5-D28E-43BB-9A0E-A91AAB6D655C.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21957\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/915BF0B5-D28E-43BB-9A0E-A91AAB6D655C.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/915BF0B5-D28E-43BB-9A0E-A91AAB6D655C.jpeg?bwg=1674075912\"                   alt=\"915BF0B5-D28E-43BB-9A0E-A91AAB6D655C\"                   title=\"915BF0B5-D28E-43BB-9A0E-A91AAB6D655C\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21958\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/0311A2D3-6385-48B3-A843-966CADC7C5E5.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21958\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0311A2D3-6385-48B3-A843-966CADC7C5E5.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0311A2D3-6385-48B3-A843-966CADC7C5E5.jpeg?bwg=1674075912\"                   alt=\"0311A2D3-6385-48B3-A843-966CADC7C5E5\"                   title=\"0311A2D3-6385-48B3-A843-966CADC7C5E5\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21959\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/C8B92BAD-B8F5-432D-A70A-C45073F9F090.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21959\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C8B92BAD-B8F5-432D-A70A-C45073F9F090.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C8B92BAD-B8F5-432D-A70A-C45073F9F090.jpeg?bwg=1674075912\"                   alt=\"C8B92BAD-B8F5-432D-A70A-C45073F9F090\"                   title=\"C8B92BAD-B8F5-432D-A70A-C45073F9F090\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21960\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/AC28DAF3-0A2C-4048-944C-57CEECA7E4C7.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21960\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AC28DAF3-0A2C-4048-944C-57CEECA7E4C7.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/AC28DAF3-0A2C-4048-944C-57CEECA7E4C7.jpeg?bwg=1674075912\"                   alt=\"AC28DAF3-0A2C-4048-944C-57CEECA7E4C7\"                   title=\"AC28DAF3-0A2C-4048-944C-57CEECA7E4C7\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21961\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/A02B36F6-A094-4A69-89AF-27BCE3FCD976.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21961\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A02B36F6-A094-4A69-89AF-27BCE3FCD976.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/A02B36F6-A094-4A69-89AF-27BCE3FCD976.jpeg?bwg=1674075912\"                   alt=\"A02B36F6-A094-4A69-89AF-27BCE3FCD976\"                   title=\"A02B36F6-A094-4A69-89AF-27BCE3FCD976\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21962\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/DEF2BE49-301D-4358-A58A-265F4EED9439.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21962\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/DEF2BE49-301D-4358-A58A-265F4EED9439.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/DEF2BE49-301D-4358-A58A-265F4EED9439.jpeg?bwg=1674075912\"                   alt=\"DEF2BE49-301D-4358-A58A-265F4EED9439\"                   title=\"DEF2BE49-301D-4358-A58A-265F4EED9439\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21963\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/96720BE2-C8AB-48A6-8F4B-93892A4B190B.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21963\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/96720BE2-C8AB-48A6-8F4B-93892A4B190B.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/96720BE2-C8AB-48A6-8F4B-93892A4B190B.jpeg?bwg=1674075912\"                   alt=\"96720BE2-C8AB-48A6-8F4B-93892A4B190B\"                   title=\"96720BE2-C8AB-48A6-8F4B-93892A4B190B\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21964\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/C6B017BD-20E3-470F-99B2-23ACAC9C21D7.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21964\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C6B017BD-20E3-470F-99B2-23ACAC9C21D7.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C6B017BD-20E3-470F-99B2-23ACAC9C21D7.jpeg?bwg=1674075912\"                   alt=\"C6B017BD-20E3-470F-99B2-23ACAC9C21D7\"                   title=\"C6B017BD-20E3-470F-99B2-23ACAC9C21D7\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21965\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/707D3BAD-A0F2-4D65-99F9-7A54A8657E0B.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21965\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/707D3BAD-A0F2-4D65-99F9-7A54A8657E0B.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/707D3BAD-A0F2-4D65-99F9-7A54A8657E0B.jpeg?bwg=1674075912\"                   alt=\"707D3BAD-A0F2-4D65-99F9-7A54A8657E0B\"                   title=\"707D3BAD-A0F2-4D65-99F9-7A54A8657E0B\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21966\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/20EF6D5E-5B58-4D60-BE7D-59379DDC4281.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21966\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/20EF6D5E-5B58-4D60-BE7D-59379DDC4281.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/20EF6D5E-5B58-4D60-BE7D-59379DDC4281.jpeg?bwg=1674075912\"                   alt=\"20EF6D5E-5B58-4D60-BE7D-59379DDC4281\"                   title=\"20EF6D5E-5B58-4D60-BE7D-59379DDC4281\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21967\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/0131E46E-5851-460F-A6BF-158F9C2BB679.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21967\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0131E46E-5851-460F-A6BF-158F9C2BB679.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/0131E46E-5851-460F-A6BF-158F9C2BB679.jpeg?bwg=1674075912\"                   alt=\"0131E46E-5851-460F-A6BF-158F9C2BB679\"                   title=\"0131E46E-5851-460F-A6BF-158F9C2BB679\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21968\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/C751F3DA-1BED-479D-9576-0F34DF72E992.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21968\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C751F3DA-1BED-479D-9576-0F34DF72E992.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/C751F3DA-1BED-479D-9576-0F34DF72E992.jpeg?bwg=1674075912\"                   alt=\"C751F3DA-1BED-479D-9576-0F34DF72E992\"                   title=\"C751F3DA-1BED-479D-9576-0F34DF72E992\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21969\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/CFEA2854-1C62-4533-8AFF-D44CDF7C800E.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21969\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/CFEA2854-1C62-4533-8AFF-D44CDF7C800E.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/CFEA2854-1C62-4533-8AFF-D44CDF7C800E.jpeg?bwg=1674075912\"                   alt=\"CFEA2854-1C62-4533-8AFF-D44CDF7C800E\"                   title=\"CFEA2854-1C62-4533-8AFF-D44CDF7C800E\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21970\" href=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/515F5BCB-22BF-47FF-A3BD-1ACC7F55B5BA.jpeg?bwg=1674075912\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0\">          <div class=\"bwg-item1\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0\"                   data-id=\"21970\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/515F5BCB-22BF-47FF-A3BD-1ACC7F55B5BA.jpeg?bwg=1674075912\"                   src=\"https:\/\/alfaisalyfc.net\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/515F5BCB-22BF-47FF-A3BD-1ACC7F55B5BA.jpeg?bwg=1674075912\"                   alt=\"515F5BCB-22BF-47FF-A3BD-1ACC7F55B5BA\"                   title=\"515F5BCB-22BF-47FF-A3BD-1ACC7F55B5BA\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">                <script>jQuery('.bwg_nav_cont_0').remove()<\/script>              <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 2;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 0);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1799606764\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0639\u0627\u062f\u0644 \u0627\u0644\u0641\u0631\u064a\u0642 \u0627\u0644\u0623\u0648\u0644 \u0644\u0643\u0631\u0629 \u0627\u0644\u0642\u062f\u0645 \u0645\u0639 \u0646\u0638\u064a\u0631\u0647 &#8220; \u0627\u0644\u0634\u0639\u0644\u0629 &#8220; \u0628\u0647\u062f\u0641 \u0644\u0643\u0644\u0645\u0646\u0647\u0645\u0627 \u060c \u0636\u0645\u0646 \u0645\u0628\u0627\u0631\u064a\u0627\u062a \u0627\u0644\u062c\u0648\u0644\u0629 \u0627\u0644\u0633\u0627\u0628\u0639\u0629 \u0639\u0634\u0631 \u0645\u0646 \u062f\u0648\u0631\u064a \u064a\u0644\u0648\u0644\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u060c \u0641\u064a \u0644\u0642\u0627\u0621 \u062c\u0645\u0639\u0647\u0645\u0627 \u0639\u0644\u0649 \u0623\u0631\u0636\u064a\u0629 \u0645\u0644\u0639\u0628 \u0645\u062f\u064a\u0646\u0629\u0627\u0644\u0645\u062c\u0645\u0639\u0629 \u0627\u0644\u0631\u064a\u0627\u0636\u064a\u0629 \u0627\u0644\u064a\u0648\u0645 \u0627\u0644\u0623\u0631\u0628\u0639\u0627\u0621 . \u0648\u0633\u062c\u0644 \u0647\u062f\u0641 \u0627\u0644\u0639\u0646\u0627\u0628\u064a \u0627\u0644\u0644\u0627\u0639\u0628 \u0635\u0627\u0644\u062d \u0627\u0644\u0642\u0645\u064a\u0632\u064a \u0639\u0646\u062f \u0627\u0644\u062f\u0642\u064a\u0642\u0629 64 \u0645\u0646 \u0632\u0645\u0646 \u0627\u0644\u0644\u0642\u0627\u0621. \u0648\u0631\u0641\u0639 \u0627\u0644\u0641\u0631\u064a\u0642 \u0631\u0635\u064a\u062f\u0647 \u0625\u0644\u0649 \u0627\u0644\u0646\u0642\u0637\u0629 34 \u0641\u064a \u0635\u062f\u0627\u0631\u0629 \u0627\u0644\u062a\u0631\u062a\u064a\u0628&#8230;.<\/p>","protected":false},"author":3,"featured_media":59576,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[386],"tags":[],"class_list":["post-59583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-first-team"],"_links":{"self":[{"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/posts\/59583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/comments?post=59583"}],"version-history":[{"count":0,"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/posts\/59583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/media\/59576"}],"wp:attachment":[{"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/media?parent=59583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/categories?post=59583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alfaisalyfc.net\/en\/wp-json\/wp\/v2\/tags?post=59583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}